{"id":2722,"date":"2024-10-31T14:20:55","date_gmt":"2024-10-31T17:20:55","guid":{"rendered":"https:\/\/cadbim.com.br\/?page_id=2722"},"modified":"2025-05-23T08:17:57","modified_gmt":"2025-05-23T11:17:57","slug":"suppliers","status":"publish","type":"page","link":"https:\/\/cadbim.com.br\/en\/fornecedores\/","title":{"rendered":"Suppliers"},"content":{"rendered":"<section class=\"bde-section-2722-100 bde-section\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay bde-section-background-overlay\"><\/div>\n\n\n<div class=\"section-container\"><div class=\"bde-columns-2722-101 bde-columns\"><div class=\"bde-column-2722-102 bde-column\">\n  \n  \n\t\n\n\n\n<div class=\"bde-text-2722-103 bde-text\">\n\n<\/div><h1 class=\"bde-heading-2722-104 bde-heading text-gradient\">\nFornecedores\n<\/h1>\n<\/div><div class=\"bde-column-2722-105 bde-column\">\n  \n  \n\t\n\n\n\n<p class=\"bde-text-2722-106 bde-text\">\nSeja nosso parceiro na transforma\u00e7\u00e3o da Engenharia e BIM! Envie seu portf\u00f3lio e venha construir o futuro com a Cadbim.\n<\/p>\n<\/div><\/div><\/div>\n<\/section><section class=\"bde-section-2722-107 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h3 class=\"bde-heading-2722-108 bde-heading\" data-entrance=\"fade\">\nFORNECEDORES\n<\/h3><div class=\"bde-grid-2722-109 bde-grid\">\n  \n  \n\t\n\n\n\n<div class=\"bde-columns-2722-110 bde-columns\"><div class=\"bde-column-2722-113 bde-column\">\n  \n  \n\t\n\n\n\n<p class=\"bde-text-2722-114 bde-text\">\nFA\u00c7A PARTE DOS NOSSOS FORNECEDORES\n<\/p>\n<\/div><\/div><div class=\"bde-div-2722-115 bde-div\">\n  \n  \n\t\n\n\n\n<p class=\"bde-text-2722-116 bde-text\">\nA Cadbim tamb\u00e9m valoriza a excel\u00eancia nas rela\u00e7\u00f5es com seus parceiros. Buscamos fornecedores comprometidos com qualidade, inova\u00e7\u00e3o e profissionalismo para juntos transformarmos a Engenharia com o BIM.\n<\/p>\n<\/div>\n<\/div><div class=\"bde-form-builder-2722-117 bde-form-builder\">\n\n<form id=\"formulario-fornecedores117\" class=\"breakdance-form breakdance-form--vertical\" data-options=\"{&quot;slug&quot;:&quot;custom&quot;,&quot;name&quot;:&quot;Formul\\u00e1rio Fornecedores&quot;,&quot;ajaxUrl&quot;:&quot;https:\\\/\\\/cadbim.com.br\\\/wp-admin\\\/admin-ajax.php&quot;,&quot;clearOnSuccess&quot;:true,&quot;hideOnSuccess&quot;:false,&quot;successMessage&quot;:&quot;Mensagem enviada com sucesso! Em breve, entraremos em contato!&quot;,&quot;errorMessage&quot;:&quot;Algo deu errado. Entre em contato conosco via telefone.&quot;,&quot;redirect&quot;:false,&quot;redirectUrl&quot;:&quot;&quot;,&quot;customJavaScript&quot;:&quot;&quot;,&quot;recaptcha&quot;:{&quot;key&quot;:&quot;&quot;,&quot;enabled&quot;:false},&quot;honeypot_enabled&quot;:false,&quot;popupsOnSuccess&quot;:[],&quot;popupsOnError&quot;:[]}\" data-steps=\"0\" >\n  \n  \n  \n<div class=\"breakdance-form-field breakdance-form-field--text\" >\n    \n    \n            <label class=\"breakdance-form-field__label\" for=\"name\">\n            Nome da empresa<span class=\"breakdance-form-field__required\">*<\/span>\n        <\/label>\n    \n    <input\n    class=\"breakdance-form-field__input\"\n    id=\"name\"\n    aria-describedby=\"name\"\n    type=\"text\"\n    name=\"fields[name]\"\n    placeholder=\"Nome da empresa*\"\n    value=\"\"\n                \n        \n        \n    required\n    \n    \n    \n    \n    \n>\n\n\n    \n    \n<\/div>\n\n\n<div class=\"breakdance-form-field breakdance-form-field--text\" >\n    \n    \n            <label class=\"breakdance-form-field__label\" for=\"website\">\n            Site<span class=\"breakdance-form-field__required\">*<\/span>\n        <\/label>\n    \n    <input\n    class=\"breakdance-form-field__input\"\n    id=\"website\"\n    aria-describedby=\"website\"\n    type=\"text\"\n    name=\"fields[website]\"\n    placeholder=\"Site*\"\n    value=\"\"\n                \n        \n        \n    required\n    \n    \n    \n    \n    \n>\n\n\n    \n    \n<\/div>\n\n\n<div class=\"breakdance-form-field breakdance-form-field--text\" >\n    \n    \n            <label class=\"breakdance-form-field__label\" for=\"social\">\n            Rede Social (Linkedin ou Instagram)<span class=\"breakdance-form-field__required\">*<\/span>\n        <\/label>\n    \n    <input\n    class=\"breakdance-form-field__input\"\n    id=\"social\"\n    aria-describedby=\"social\"\n    type=\"text\"\n    name=\"fields[social]\"\n    placeholder=\"Rede Social* (Linkedin ou Instagram)\"\n    value=\"\"\n                \n        \n        \n    required\n    \n    \n    \n    \n    \n>\n\n\n    \n    \n<\/div>\n\n\n<div class=\"breakdance-form-field breakdance-form-field--email\" >\n    \n    \n            <label class=\"breakdance-form-field__label\" for=\"email\">\n            E-mail<span class=\"breakdance-form-field__required\">*<\/span>\n        <\/label>\n    \n    <input\n    class=\"breakdance-form-field__input\"\n    id=\"email\"\n    aria-describedby=\"email\"\n    type=\"email\"\n    name=\"fields[email]\"\n    placeholder=\"E-mail*\"\n    value=\"\"\n                \n        \n        \n    required\n    \n    \n    \n    \n    \n>\n\n\n    \n    \n<\/div>\n\n\n<div class=\"breakdance-form-field breakdance-form-field--tel\" >\n    \n    \n            <label class=\"breakdance-form-field__label\" for=\"phone\">\n            Telefone<span class=\"breakdance-form-field__required\">*<\/span>\n        <\/label>\n    \n    <input\n    class=\"breakdance-form-field__input\"\n    id=\"phone\"\n    aria-describedby=\"phone\"\n    type=\"tel\"\n    name=\"fields[phone]\"\n    placeholder=\"Telefone ou WhatsApp*\"\n    value=\"\"\n                \n        \n        \n    required\n    \n    \n    \n    \n    \n>\n\n\n    \n    \n<\/div>\n\n\n<div class=\"breakdance-form-field breakdance-form-field--file\" >\n    \n    \n            <label class=\"breakdance-form-field__label\" for=\"portfolio\">\n            Anexos (Portf\u00f3lio ou apresenta\u00e7\u00e3o institucional)<span class=\"breakdance-form-field__required\">*<\/span>\n        <\/label>\n    \n    <label for=\"portfolio\" class=\"breakdance-form-file-upload\">\n\n                \n    \n    \n    \n    \n            \n            <button type=\"button\" class=\"button-atom button-atom--secondary breakdance-form-file-upload__button\"  >\n    \n        <span class=\"button-atom__text\">Choose File<\/span>\n\n        \n        \n            <\/button>\n    \n        <span class=\"breakdance-form-file-upload__text\">\n            No file chosen\n        <\/span>\n    \n    <input\n        id=\"portfolio\"\n        name=\"fields[portfolio][]\"\n        type=\"file\"\n        class=\"breakdance-form-file-upload__input\"\n        accept=\"application\/pdf,application\/vnd.openxmlformats-officedocument.wordprocessingml.document,application\/msword\"\n        \n        required\n        \n                data-max-files=\"\"\n        data-i18n-empty-text=\"No file chosen\"\n        data-i18n-filled-text=\"%n files\"\n        data-i18n-error-text=\"Only %n file(s) allowed.\"\n    >\n<\/label>\n\n\n\n    \n    \n<\/div><div class=\"breakdance-form-field breakdance-form-footer\">    \n    \n    \n    \n    \n            \n            <button type=\"submit\" class=\"button-atom button-atom--primary breakdance-form-button breakdance-form-button__submit\"  >\n    \n        <span class=\"button-atom__text\">Enviar mensagem<\/span>\n\n        \n        \n            <\/button>\n    \n    <input type=\"hidden\" name=\"form_id\" value=\"117\">\n    <input type=\"hidden\" name=\"post_id\" value=\"2722\">\n<\/div>\n\n  \n<\/form>\n\n\n<\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Fornecedores Seja nosso parceiro na transforma\u00e7\u00e3o da Engenharia e BIM! Envie seu portf\u00f3lio e venha construir o futuro com a Cadbim. FORNECEDORES FA\u00c7A PARTE DOS NOSSOS FORNECEDORES A Cadbim tamb\u00e9m valoriza a excel\u00eancia nas rela\u00e7\u00f5es com seus parceiros. Buscamos fornecedores comprometidos com qualidade, inova\u00e7\u00e3o e profissionalismo para juntos transformarmos a Engenharia com o BIM. Nome [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_breakdance_hide_in_design_set":false,"_breakdance_tags":"","footnotes":""},"class_list":["post-2722","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/cadbim.com.br\/en\/wp-json\/wp\/v2\/pages\/2722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cadbim.com.br\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cadbim.com.br\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cadbim.com.br\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/cadbim.com.br\/en\/wp-json\/wp\/v2\/comments?post=2722"}],"version-history":[{"count":12,"href":"https:\/\/cadbim.com.br\/en\/wp-json\/wp\/v2\/pages\/2722\/revisions"}],"predecessor-version":[{"id":2958,"href":"https:\/\/cadbim.com.br\/en\/wp-json\/wp\/v2\/pages\/2722\/revisions\/2958"}],"wp:attachment":[{"href":"https:\/\/cadbim.com.br\/en\/wp-json\/wp\/v2\/media?parent=2722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}